{"id":1,"count":2,"description":"","link":"https:\/\/sunlaws.com.au\/zh\/category\/uncategorised\/","name":"Uncategorised","slug":"uncategorised","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/sunlaws.com.au\/zh\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sunlaws.com.au\/zh\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sunlaws.com.au\/zh\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sunlaws.com.au\/zh\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}